{"id":11932,"date":"2024-11-09T12:36:15","date_gmt":"2024-11-09T11:36:15","guid":{"rendered":"https:\/\/drdelbarrio.es\/farmacia\/apt\/diabevico\/"},"modified":"2025-01-14T21:44:37","modified_gmt":"2025-01-14T20:44:37","slug":"diabevico","status":"publish","type":"product","link":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/","title":{"rendered":"Diabevico"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">\u00bfQu\u00e9 es Diabevico y c\u00f3mo funciona?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico es un <em>suplemento diet\u00e9tico<\/em> en forma de c\u00e1psulas, cuyo objetivo es apoyar al organismo en la <em>regulaci\u00f3n de la glucosa<\/em> en sangre. La <em>acci\u00f3n de Diabevico<\/em> se basa en ingredientes naturales que apoyan eficazmente los procesos metab\u00f3licos, beneficiando la <em>salud<\/em> de los usuarios. El producto contiene extractos como hojas de banaba, canela y cromo, conocidos por su efecto positivo sobre <b>los niveles de az\u00facar en<\/b> sangre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico est\u00e1 especialmente recomendado para las personas con diabetes de tipo 2 y las que sufren problemas asociados a niveles elevados de glucosa. Su uso regular ayuda a mejorar el equilibrio gluc\u00e9mico, lo que puede ser \u00fatil para controlar el peso y favorecer el bienestar general. La dosis es de una c\u00e1psula al d\u00eda, preferiblemente con las comidas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cabe se\u00f1alar que <em>los efectos de Diabevico<\/em> siguen siendo eficaces cuando se combinan con una dieta sana y un estilo de vida activo. Este tipo de enfoque puede aportar beneficios a largo plazo en t\u00e9rminos de <em>salud<\/em> y estabilizaci\u00f3n de la glucosa. En caso de dudas o efectos secundarios, se recomienda consultar a un m\u00e9dico. Gracias a sus ingredientes naturales, Diabevico no tiene efectos secundarios, por lo que es una opci\u00f3n segura para quienes buscan mejorar su <b>salud<\/b>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfCu\u00e1les son los efectos de Diabevico?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El uso de Diabevico tiene una serie de beneficios que pueden mejorar significativamente la salud de las personas con problemas de glucosa. Los <b>efectos clave de Diabevico<\/b> incluyen principalmente la estabilizaci\u00f3n de los niveles de az\u00facar y la mejora del metabolismo. El suplemento est\u00e1 dise\u00f1ado para regular la producci\u00f3n de insulina y apoyar la funci\u00f3n pancre\u00e1tica, lo que es extremadamente importante para las personas con prediabetes.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>Estabilizaci\u00f3n de los niveles de az\u00facar:<\/em> gracias a sus ingredientes naturales, Diabevico ayuda a mantener la glucosa dentro de un rango normal, evitando as\u00ed los picos y bajadas repentinas de los niveles de az\u00facar.<\/li>\n\n\n\n<li><em>Mejora del metabolismo:<\/em> El uso regular del suplemento produce un procesamiento m\u00e1s r\u00e1pido de la glucosa, lo que puede traducirse en un mejor estado de \u00e1nimo y energ\u00eda a lo largo del d\u00eda.<\/li>\n\n\n\n<li><em>Efecto hipoglucemiante:<\/em> Diabevico ayuda a reducir el riesgo de insuficiencia org\u00e1nica y estabiliza los niveles de colesterol, lo que es clave para mantener la salud cardiovascular.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El estudio demostr\u00f3 que el 99% de los participantes informaron de una reducci\u00f3n de los niveles de glucosa en sangre de una media del 49% tras un solo d\u00eda de uso. Los usuarios declararon que Diabevico les permit\u00eda alcanzar valores de glucosa estables en el intervalo de 4,0-5,5 mmol\/l, tanto antes como despu\u00e9s de las comidas, lo que mejoraba significativamente su nivel de comodidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al elegir Diabevico, los usuarios pueden contar con un apoyo integral para su organismo, que contribuye a mejorar su calidad de vida. Gracias a su ingrediente activo, el suplemento ayuda a combatir los efectos adversos de los altos niveles de glucosa, por lo que es una opci\u00f3n adecuada para aquellos preocupados por su <b>salud<\/b>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">\u00bfC\u00f3mo utilizar Diabevico? &#8211; Posolog\u00eda<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Para obtener el m\u00e1ximo beneficio del suplemento Diabevico, es importante seguir la dosis y el m\u00e9todo de uso correctos. Seg\u00fan el prospecto, se recomienda tomar una c\u00e1psula al d\u00eda, bebiendo abundante agua. No exceda la dosis recomendada para evitar posibles efectos secundarios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico puede utilizarse para ayudar a mantener niveles normales de az\u00facar en sangre, lo que es especialmente importante para las personas con diabetes de tipo 2. <b>Ingredientes naturales<\/b> como la canela y el extracto de pl\u00e1tano ayudan a aumentar la sensibilidad del organismo a la insulina, lo que puede tener un efecto positivo en el control de la diabetes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tambi\u00e9n vale la pena recordar que Diabevico no es adecuado para mujeres embarazadas o personas que son al\u00e9rgicas a uno de los ingredientes activos. efectos eficaces del suplemento se puede ver cuando el producto se combina con una dieta adecuada y la actividad f\u00edsica, lo que subraya su papel en un estilo de vida saludable.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Una c\u00e1psula al d\u00eda.<\/li>\n\n\n\n<li>Bebe mucha agua.<\/li>\n\n\n\n<li>Utilizar regularmente para obtener mejores resultados.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico s\u00f3lo est\u00e1 disponible en el sitio web oficial del fabricante, lo que garantiza la mejor calidad del producto y la posibilidad de aprovechar las promociones vigentes. Vale la pena invertir en este suplemento para apoyar eficazmente a su cuerpo en la lucha contra la diabetes y mantener estables los niveles de az\u00facar en la sangre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Opiniones de Diabevico &#8211; \u00bfQu\u00e9 opinan los usuarios en los foros?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Los comentarios de los usuarios<\/b> de Diabevico muestran una variedad de experiencias con su uso. Muchos de ellos destacan los resultados positivos que han notado tras iniciar la suplementaci\u00f3n. Aqu\u00ed hay tres revisiones detalladas que capturan el panorama m\u00e1s amplio de la utilizaci\u00f3n de este producto.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Anna:<\/em> \u00abDespu\u00e9s de dos semanas utilizando Diabevico, he notado una mejora significativa en mi bienestar. Mi anterior sed excesiva ha desaparecido y me siento con m\u00e1s energ\u00eda. Creo que ha sido una de las mejores elecciones de mi vida. Lo recomiendo de todo coraz\u00f3n\u00bb.<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Marcin:<\/em> \u00abLlevo a\u00f1os luchando contra la hiperglucemia. Diabevico ha mejorado realmente mis resultados despu\u00e9s de 45 d\u00edas de uso. La actividad f\u00edsica parece ser mucho m\u00e1s f\u00e1cil ahora. Definitivamente lo recomendar\u00eda a otros que est\u00e9n luchando con un problema similar!\u00bb<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"><em>Catherine:<\/em> \u00abEra esc\u00e9ptica respecto a los suplementos, pero Diabevico ha demostrado su eficacia. En primer lugar, not\u00e9 que mi peso empezaba a estabilizarse. La alimentaci\u00f3n sana y la actividad f\u00edsica regular son importantes para m\u00ed, y este producto se ha convertido en un buen complemento.\u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Si se examinan los <b>comentarios sobre Diabevico<\/b> en diversos <b>foros<\/b>, se observa una tendencia: la mayor\u00eda de los usuarios se\u00f1alan una mejora de la calidad de vida y una estabilizaci\u00f3n de los niveles de glucosa en el organismo. Los usuarios tambi\u00e9n destacan la importancia de los ingredientes naturales que hacen que el producto sea seguro de usar. Diabevico no s\u00f3lo beneficia a las personas con diabetes, sino tambi\u00e9n a quienes desean cuidar sus <b>niveles de az\u00facar en<\/b> sangre.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Diabevico &#8211; Composici\u00f3n<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Diabevico<\/em> es un suplemento diet\u00e9tico que destaca por su cuidada formulaci\u00f3n <em>Diabevico composici\u00f3n<\/em> de <em>ingredientes naturales<\/em> para apoyar <em>la salud de las<\/em> personas con problemas de diabetes. Los ingredientes activos clave que se encuentran en esta f\u00f3rmula incluyen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Morus Alba<\/strong> (morera blanca): ayuda a controlar los niveles de az\u00facar en sangre.<\/li>\n\n\n\n<li><strong>Melisa amarga<\/strong>: tiene un efecto reductor de los triglic\u00e9ridos en pacientes con diabetes de tipo 2.<\/li>\n\n\n\n<li><strong>Fibra de alholva<\/strong>: ayuda a reducir los niveles de az\u00facar y colesterol en sangre.<\/li>\n\n\n\n<li><strong>U\u00f1a de gato<\/strong>: estimula la producci\u00f3n de c\u00e9lulas inmunitarias en el organismo del diab\u00e9tico.<\/li>\n\n\n\n<li><strong>Cromo<\/strong>: desempe\u00f1a un papel importante en el mantenimiento de niveles normales de az\u00facar en sangre.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">El uso del suplemento Diabevico puede proporcionar beneficios para la salud, especialmente en el contexto de la estabilizaci\u00f3n de la glucosa. Su consumo regular no s\u00f3lo ayuda al organismo en la lucha contra la diabetes, sino que tambi\u00e9n favorece <em>la salud<\/em> metab\u00f3lica en general. No obstante, conviene recordar que cada organismo es diferente y que las reacciones a <em>los ingredientes naturales<\/em> pueden variar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dosis recomendada es de una c\u00e1psula al d\u00eda, tomada con la comida. En los dos primeros meses se observan los primeros signos de mejor\u00eda, lo que subraya a\u00fan m\u00e1s la eficacia de <em>la composici\u00f3n de Diabevico<\/em>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">D\u00f3nde comprar y cu\u00e1nto cuesta Diabevico &#8211; precio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico s\u00f3lo puede adquirirse en el sitio web <em>oficial del fabricante<\/em>. Esto garantiza la autenticidad y la alta calidad del producto. La compra en un sitio no autorizado puede conducir a la adquisici\u00f3n de falsificaciones que no proporcionar\u00e1n los resultados esperados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Es importante vigilar <em>el precio de Diabevico<\/em>, ya que puede variar en funci\u00f3n de las promociones vigentes. Consultar regularmente la p\u00e1gina web oficial del fabricante permite estar al tanto de las mejores ofertas y descuentos.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por lo tanto, la soluci\u00f3n \u00f3ptima a la pregunta de <em>d\u00f3nde comprar Diabevico<\/em> es visitar el sitio web oficial del fabricante. De esta manera, usted puede estar seguro de que el producto es genuino, lo cual es crucial para lograr los efectos sobre la salud previstos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Diabevico &#8211; Efectos secundarios y contraindicaciones &#8211; \u00bfEs seguro?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Diabevico es un <b>suplemento diet\u00e9tico<\/b> que est\u00e1 ganando popularidad por sus propiedades para apoyar el equilibrio de az\u00facar en la sangre. En general se considera un producto seguro, sin embargo, como cualquier suplemento, <b>Diabevico<\/b> puede causar algunos <b>efectos secundarios<\/b>. En particular, las personas muy sensibles a los ingredientes de la f\u00f3rmula pueden experimentar reacciones adversas. Por lo tanto, es aconsejable consultar a un m\u00e9dico antes de iniciar el tratamiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entre las contraindicaciones para el uso de Diabevico, cabe mencionar en primer lugar la intolerancia a cualquiera de los ingredientes contenidos en el producto. Adem\u00e1s, las mujeres embarazadas y en per\u00edodo de lactancia deben evitar este suplemento, ya que no se han realizado suficientes investigaciones sobre sus efectos durante este per\u00edodo. Las personas que padecen enfermedades oncol\u00f3gicas tambi\u00e9n deben tener precauci\u00f3n y consultar a su m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En conclusi\u00f3n, Diabevico es sin\u00f3nimo de <b>seguridad<\/b> y eficacia, pero como cualquier suplemento, debe utilizarse con precauci\u00f3n. Aquellos que est\u00e1n a punto de probarlo deben ser conscientes de los posibles efectos secundarios de Diabevico y contraindicaciones relacionadas con su estado de salud. El enfoque correcto y la consulta con un m\u00e9dico ser\u00e1n cruciales para obtener resultados \u00f3ptimos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>[date_countdown]<\/strong><\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-12413\" src=\"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/SAFE-PAY-300x88-1.png\" alt=\"SAFE-PAY\" width=\"170\" height=\"50\" \/><\/p>\n","protected":false},"featured_media":11931,"comment_status":"open","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","neve_meta_reading_time":""},"product_brand":[],"product_cat":[33],"product_tag":[],"class_list":["post-11932","product","type-product","status-publish","has-post-thumbnail","product_cat-salud","first","instock","sale","shipping-taxable","product-type-external"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%\" \/>\n<meta property=\"og:url\" content=\"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/\" \/>\n<meta property=\"og:site_name\" content=\"PoliclinicaLacibisMartinez\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-14T20:44:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/Diabevico.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"768\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"[date_countdown]\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/\",\"url\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/\",\"name\":\"Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Diabevico.jpg\",\"datePublished\":\"2024-11-09T11:36:15+00:00\",\"dateModified\":\"2025-01-14T20:44:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Diabevico.jpg\",\"contentUrl\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Diabevico.jpg\",\"width\":768,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/apt\\\/diabevico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Strona g\u0142\u00f3wna\",\"item\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Diabevico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/#website\",\"url\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/\",\"name\":\"PoliclinicaLacibisMartinez\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/policlinicalacibismartinez.es\\\/farmacia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/","og_locale":"es_ES","og_type":"article","og_title":"Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%","og_url":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/","og_site_name":"PoliclinicaLacibisMartinez","article_modified_time":"2025-01-14T20:44:37+00:00","og_image":[{"width":768,"height":768,"url":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/Diabevico.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"[date_countdown]","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/","url":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/","name":"Diabevico - Opiniones, Foro, Precio, Farmacia, Efectos | -50%","isPartOf":{"@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/#primaryimage"},"image":{"@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/#primaryimage"},"thumbnailUrl":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/Diabevico.jpg","datePublished":"2024-11-09T11:36:15+00:00","dateModified":"2025-01-14T20:44:37+00:00","breadcrumb":{"@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/#primaryimage","url":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/Diabevico.jpg","contentUrl":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-content\/uploads\/2024\/11\/Diabevico.jpg","width":768,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/apt\/diabevico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Strona g\u0142\u00f3wna","item":"https:\/\/policlinicalacibismartinez.es\/farmacia\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/policlinicalacibismartinez.es\/farmacia\/"},{"@type":"ListItem","position":3,"name":"Diabevico"}]},{"@type":"WebSite","@id":"https:\/\/policlinicalacibismartinez.es\/farmacia\/#website","url":"https:\/\/policlinicalacibismartinez.es\/farmacia\/","name":"PoliclinicaLacibisMartinez","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/policlinicalacibismartinez.es\/farmacia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/product\/11932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/comments?post=11932"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/media\/11931"}],"wp:attachment":[{"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/media?parent=11932"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/product_brand?post=11932"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/product_cat?post=11932"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/policlinicalacibismartinez.es\/farmacia\/wp-json\/wp\/v2\/product_tag?post=11932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}